{"id":20182,"date":"2024-10-24T09:28:33","date_gmt":"2024-10-24T07:28:33","guid":{"rendered":"https:\/\/www.soralia.be\/accueil\/?post_type=tribe_events&#038;p=20182"},"modified":"2024-10-24T09:28:33","modified_gmt":"2024-10-24T07:28:33","slug":"exposition-les-crocodiles-sont-toujours-la-a-nivelles","status":"publish","type":"tribe_events","link":"https:\/\/www.soralia.be\/accueil\/event\/exposition-les-crocodiles-sont-toujours-la-a-nivelles\/","title":{"rendered":"Exposition &#8211; \u201cLes crocodiles sont toujours l\u00e0\u201d \u00e0 Nivelles"},"content":{"rendered":"<h3>Dans le cadre du projet de sensibilisation contre les violences faites aux femmes<\/h3>\n<p>\u270b\u00a0<u>Exposition<\/u>\u00a0\u201cLes crocodiles sont toujours l\u00e0 !\u201d, une r\u00e9alisation de Juliette Boutant &amp; Thomas Mathieu \/ Casterman.<\/p>\n<p>Cette exposition illustre des t\u00e9moignages de femmes li\u00e9s aux probl\u00e9matiques comme le harc\u00e8lement de rue, le sexisme ordinaire et les violences sexistes et sexuelles dans les espaces publics et priv\u00e9s.<\/p>\n<p>+\u00a0<strong>Un\u00a0<u>atelier collectif\u00a0<\/u>est propos\u00e9 (inscription obligatoire) le mercredi 27 novembre de 14h \u00e0 16h<\/strong>\u00a0pour apprendre la r\u00e9partie pour faire face aux remarques sexistes dans la rue<\/p>\n<p>\u26a0\ufe0f\u00a0Visites libres ou animations sur demande\u00a0: annabelle.duaut@laicite.net ou 0473 53 32 89<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-20184 size-full\" src=\"https:\/\/www.soralia.be\/wp-content\/uploads\/2024\/10\/Soralia-Ruban-blanc-Nivelles-crocodiles.jpg\" alt=\"\" width=\"1865\" height=\"854\" srcset=\"https:\/\/www.soralia.be\/wp-content\/uploads\/2024\/10\/Soralia-Ruban-blanc-Nivelles-crocodiles-200x92.jpg 200w, https:\/\/www.soralia.be\/wp-content\/uploads\/2024\/10\/Soralia-Ruban-blanc-Nivelles-crocodiles-300x137.jpg 300w, https:\/\/www.soralia.be\/wp-content\/uploads\/2024\/10\/Soralia-Ruban-blanc-Nivelles-crocodiles-400x183.jpg 400w, https:\/\/www.soralia.be\/wp-content\/uploads\/2024\/10\/Soralia-Ruban-blanc-Nivelles-crocodiles-600x275.jpg 600w, https:\/\/www.soralia.be\/wp-content\/uploads\/2024\/10\/Soralia-Ruban-blanc-Nivelles-crocodiles-768x352.jpg 768w, https:\/\/www.soralia.be\/wp-content\/uploads\/2024\/10\/Soralia-Ruban-blanc-Nivelles-crocodiles-800x366.jpg 800w, https:\/\/www.soralia.be\/wp-content\/uploads\/2024\/10\/Soralia-Ruban-blanc-Nivelles-crocodiles-1024x469.jpg 1024w, https:\/\/www.soralia.be\/wp-content\/uploads\/2024\/10\/Soralia-Ruban-blanc-Nivelles-crocodiles-1200x549.jpg 1200w, https:\/\/www.soralia.be\/wp-content\/uploads\/2024\/10\/Soralia-Ruban-blanc-Nivelles-crocodiles-1536x703.jpg 1536w, https:\/\/www.soralia.be\/wp-content\/uploads\/2024\/10\/Soralia-Ruban-blanc-Nivelles-crocodiles.jpg 1865w\" sizes=\"(max-width: 1865px) 100vw, 1865px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h3>Infos pratiques<\/h3>\n<div class=\"fusion-li-item-content\">\ud83d\udcc6 <strong>Date<\/strong> : Du 21 au 29 novembre<br \/>\n\ud83d\udccd <strong>Lieu<\/strong> : La\u00efcit\u00e9 Brabant wallon &#8211; Rue Georges Willame, 10 \u00e0 Nivelles<\/div>\n<div class=\"fusion-li-item-content\">\ud83d\udcb0 <strong>Prix<\/strong> : Gratuit<br \/>\n\u26a0\ufe0f Visites libres ou animations sur demande via le contact<\/div>\n<div class=\"fusion-li-item-content\">\ud83d\udcde <strong>Contact\u00a0<\/strong>: annabelle.duaut@laicite.net ou 0473 53 32 89<\/div>\n<div class=\"fusion-li-item-content\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e8s 18 ans<\/p>\n","protected":false},"author":29,"featured_media":1074,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[9],"tribe_events_cat":[123,166,87],"class_list":["post-20182","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-violences","tribe_events_cat-brabant-wallon","tribe_events_cat-culture","tribe_events_cat-violences","cat_brabant-wallon","cat_culture","cat_violences"],"_links":{"self":[{"href":"https:\/\/www.soralia.be\/accueil\/wp-json\/wp\/v2\/tribe_events\/20182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.soralia.be\/accueil\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.soralia.be\/accueil\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.soralia.be\/accueil\/wp-json\/wp\/v2\/users\/29"}],"version-history":[{"count":1,"href":"https:\/\/www.soralia.be\/accueil\/wp-json\/wp\/v2\/tribe_events\/20182\/revisions"}],"predecessor-version":[{"id":20185,"href":"https:\/\/www.soralia.be\/accueil\/wp-json\/wp\/v2\/tribe_events\/20182\/revisions\/20185"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.soralia.be\/accueil\/wp-json\/wp\/v2\/media\/1074"}],"wp:attachment":[{"href":"https:\/\/www.soralia.be\/accueil\/wp-json\/wp\/v2\/media?parent=20182"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.soralia.be\/accueil\/wp-json\/wp\/v2\/tags?post=20182"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.soralia.be\/accueil\/wp-json\/wp\/v2\/tribe_events_cat?post=20182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}