{"id":7629,"date":"2019-01-31T10:00:28","date_gmt":"2019-01-31T09:00:28","guid":{"rendered":"http:\/\/www.soralia.be\/?post_type=tribe_events&#038;p=7629"},"modified":"2019-01-31T11:35:05","modified_gmt":"2019-01-31T10:35:05","slug":"etes-vous-pret-es-a-aller-mieux-wanfercee-baulet-2","status":"publish","type":"tribe_events","link":"https:\/\/www.soralia.be\/accueil\/event\/etes-vous-pret-es-a-aller-mieux-wanfercee-baulet-2\/","title":{"rendered":"\u00cates-vous pr\u00eat.es \u00e0 aller mieux? [Wanferc\u00e9e-Baulet]"},"content":{"rendered":"<p>Soralia de Charleroi vous proposent des ateliers pour se construire une valise \u00e0 outils \u00e0 utiliser afin d&rsquo;aller mieux, de devenir acteur.rice de sa vie et reprendre les rennes de sa sant\u00e9 mentale.<br \/>\nComment? En d\u00e9couvrant la mise en \u00e9vidence et l\u2019analyse de facteurs facilitant la sant\u00e9 mentale dans un cadre collectif (g\u00e9rer ses \u00e9motions, d\u00e9velopper sa confiance en soi, et apprendre \u00e0 communiquer de mani\u00e8re\u2013non violente, apprendre \u00e0 g\u00e9rer les conflits, r\u00e9aliser un objectif de vie, \u2026)<br \/>\nDans une atmosph\u00e8re s\u00e9curisante, chaleureuse et respectueuse de chacun.e, les 12 modules seront synonymes de mieux-\u00eatre.<\/p>\n<p>Les participants s\u2019engagent pour l\u2019enti\u00e8ret\u00e9 du module.<\/p>\n<p>Dates:<br \/>\n26 mars<br \/>\n2, 16, 23 et 30 avril<br \/>\n7, 14, 21 et 28 mai<br \/>\n4, 11 et 18 juin<\/p>\n<p>Infos &amp; inscriptions:<br \/>\nRolanda Antonacci: 0471\/345.868 ou rolanda.antonacci@solidaris.be<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Soralia de Charleroi vous proposent des ateliers pour se construire une valise \u00e0 outils \u00e0 utiliser afin d&rsquo;aller mieux, de devenir acteur.rice de sa vie et reprendre les rennes de sa sant\u00e9 mentale. Comment? En d\u00e9couvrant la mise en \u00e9vidence et l\u2019analyse de facteurs facilitant la sant\u00e9 mentale dans un  [&#8230;]<\/p>\n","protected":false},"author":8,"featured_media":1066,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[153,144,165],"tribe_events_cat":[73,76],"class_list":["post-7629","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-confiance-en-soi","tag-developpement-personnel","tag-sante-mentale","tribe_events_cat-charleroi","tribe_events_cat-regional","cat_charleroi","cat_regional"],"_links":{"self":[{"href":"https:\/\/www.soralia.be\/accueil\/wp-json\/wp\/v2\/tribe_events\/7629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.soralia.be\/accueil\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.soralia.be\/accueil\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.soralia.be\/accueil\/wp-json\/wp\/v2\/users\/8"}],"version-history":[{"count":2,"href":"https:\/\/www.soralia.be\/accueil\/wp-json\/wp\/v2\/tribe_events\/7629\/revisions"}],"predecessor-version":[{"id":7688,"href":"https:\/\/www.soralia.be\/accueil\/wp-json\/wp\/v2\/tribe_events\/7629\/revisions\/7688"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.soralia.be\/accueil\/wp-json\/wp\/v2\/media\/1066"}],"wp:attachment":[{"href":"https:\/\/www.soralia.be\/accueil\/wp-json\/wp\/v2\/media?parent=7629"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.soralia.be\/accueil\/wp-json\/wp\/v2\/tags?post=7629"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.soralia.be\/accueil\/wp-json\/wp\/v2\/tribe_events_cat?post=7629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}